{"id":945,"date":"2024-12-15T15:27:11","date_gmt":"2024-12-15T15:27:11","guid":{"rendered":"https:\/\/esrenens.ch\/lemon\/?p=945"},"modified":"2024-12-15T15:48:58","modified_gmt":"2024-12-15T15:48:58","slug":"louragan-helene","status":"publish","type":"post","link":"https:\/\/esrenens.ch\/lemon\/louragan-helene\/","title":{"rendered":"L&rsquo;ouragan Helene\u00a0"},"content":{"rendered":"\n<p>L\u2019ouragan Helene s\u2019est form\u00e9 le 24 septembre 2024. Il apparait pour la premi\u00e8re fois au sud-est du Mexique (p\u00e9ninsule du Yucat\u00e1n) car il est devenu assez fort pour \u00eatre rep\u00e9r\u00e9. C\u2019est un ouragan de cat\u00e9gorie 4 (vent de 210-249km\/h). Il a atteint la terre le 26 septembre proche de la ville de Perry, en Floride. Apr\u00e8s avoir touch\u00e9 terre, il s\u2019est rapidement calm\u00e9 r\u00e9gressant \u00e0 l\u2019\u00e9tat de cyclone post-tropical au-dessus de l\u2019\u00e9tat du Tennessee avant de se dissiper totalement le 27 septembre. Le passage de l\u2019ouragan a eu un impact important, dont voici les plus graves.&nbsp;<\/p>\n\n\n\n<p>Au Mexique, autour de la r\u00e9gion de l\u2019\u00c9tat de Quintana Roo, plus de 120 milles clients de la compagnie <em>Comisi\u00f3n Federal de Electricidad<\/em> (Commission F\u00e9d\u00e9rale de l\u2019\u00c9lectricit\u00e9) n\u2019avaient plus d\u2019\u00e9lectricit\u00e9 ;&nbsp;<\/p>\n\n\n\n<p>Des arbres sont tomb\u00e9s et des toits ont \u00e9t\u00e9 endommag\u00e9s dans toute la p\u00e9ninsule du Yucat\u00e1n ;&nbsp;<\/p>\n\n\n\n<p>En Floride, deux prisons n\u2019ont pas \u00e9t\u00e9 \u00e9vacu\u00e9es malgr\u00e9 les ordres. Au total, 2500 prisonniers n\u2019ont pas \u00e9t\u00e9 \u00e9vacu\u00e9 l\u2019\u00c9tat a \u00e9t\u00e9 pris de court et a d\u00fb abandonner des prisonniers \u00e0 leur sort.&nbsp;<\/p>\n\n\n\n<p>Finalement, aux USA, il y a eu plus de 234 morts et 26 personnes disparues et plus de 89 millions de dollars de d\u00e9g\u00e2ts.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Inondations en Espagne<\/strong>&nbsp;<\/p>\n\n\n\n<p>L&rsquo;ouragan Helene n\u2019est pas la seule catastrophe li\u00e9e \u00e0 l\u2019eau r\u00e9cemment. Les inondations en Espagne sont aussi l\u00e0. Ce ph\u00e9nom\u00e8ne s\u2019appelle la goutte d\u2019eau, elle a fait 255 morts et 2,5 milliards d\u2019euros de d\u00e9g\u00e2ts mais que ce passe-t-il ?&nbsp;<\/p>\n\n\n\n<p>Eh bien, c\u2019est li\u00e9 \u00e0 deux facteurs. Premi\u00e8rement, la saison des ouragans et deuxi\u00e8mement, le r\u00e9chauffement climatique. Pour le premier, disons simplement que la saison des ouragans est aussi la saison des \u00e9v\u00e8nements climatiques li\u00e9s \u00e0 l\u2019eau partout dans le monde. Deuxi\u00e8mement, le r\u00e9chauffement climatique chauffe l\u2019atmosph\u00e8re qui chauffe l\u2019eau \u00e0 son tour, les ouragans ont besoin d\u2019eau chaude pour faire de la vapeur en gros plus l\u2019eau est chaude plus c\u2019est simple pour un ouragan de se former, exister, grandir.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ouragan Helene s\u2019est form\u00e9 le 24 septembre 2024. Il apparait pour la premi\u00e8re fois au sud-est du Mexique (p\u00e9ninsule du Yucat\u00e1n) car il est devenu assez fort pour \u00eatre rep\u00e9r\u00e9. C\u2019est un ouragan de cat\u00e9gorie 4 (vent de 210-249km\/h). Il a atteint la terre le 26 septembre proche de la ville de Perry, en Floride&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":970,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde_et_nous"],"_links":{"self":[{"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/posts\/945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/comments?post=945"}],"version-history":[{"count":1,"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/posts\/945\/revisions"}],"predecessor-version":[{"id":946,"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/posts\/945\/revisions\/946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/media\/970"}],"wp:attachment":[{"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/media?parent=945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/categories?post=945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esrenens.ch\/lemon\/wp-json\/wp\/v2\/tags?post=945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}